{"id":11634,"date":"2020-07-28T09:49:38","date_gmt":"2020-07-28T07:49:38","guid":{"rendered":"http:\/\/fmsb.disstintbeta.com\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/"},"modified":"2020-07-28T09:49:38","modified_gmt":"2020-07-28T07:49:38","slug":"marga-sanso-abogada-tironero-manacor-robo-violencia","status":"publish","type":"post","link":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/","title":{"rendered":"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel"},"content":{"rendered":"<p>La abogada de <strong><a class=\"profileLink\" href=\"https:\/\/www.facebook.com\/FMSB.Abogados\/?__tn__=K-R&amp;eid=ARB9qyKg-acJ_9p6wFbxjKXVMCorfTOY26UQv830L7QUCZ9tmcsZPcSUpUPjO0IWw4iocExLRaPVTG6B&amp;fref=mentions&amp;__xts__%5B0%5D=68.ARB1sO15keNPy0KYjgwc8lpBAKFEGY7HiyDoz5Iacy1vPP3_r4aONURDT9OsMg0ZCf2Nu0pzl-kNtoMMIWGlQsBwIhFnhhObmbCnJVJ_epkr7TLIuwULv-ypYwB_2PdxbNCs23CpfUW-6bl6Qk35SagmObo64A1FiGX7RRQfrGVcxehzkd8PTM-8ShNRAuIZvVCKXr7ldFi9ol7FdUyAGOArIJdCCboZYdg5I1fezAujQIUDosl-5dxn6MTIu52cSIWTFuXNT2HV9peMwDXY9fNOq9p0-gb1o9H-YbduTOOT1SZQ1OQ87bS0fCSvWSL7qavNZ1Bzwpox_pStQYSo5lAmnzRu\" data-hovercard=\"\/ajax\/hovercard\/page.php?id=1537311023226624&amp;extragetparams=%7B%22__tn__%22%3A%22%2CdK-R-R%22%2C%22eid%22%3A%22ARB9qyKg-acJ_9p6wFbxjKXVMCorfTOY26UQv830L7QUCZ9tmcsZPcSUpUPjO0IWw4iocExLRaPVTG6B%22%2C%22fref%22%3A%22mentions%22%7D\" data-hovercard-prefer-more-content-show=\"1\">Font Mora Sainz de Baranda<\/a><\/strong> <a class=\"profileLink\" title=\"Marga Sans\u00f3 Jaume\" href=\"https:\/\/www.facebook.com\/marga.sansojaume?__tn__=K-R&amp;eid=ARAU3Z1rGqia2cAcQKuXK9Z_K2D-dne6lEpoyDTdYrArqmvNWW6ax8ZjRSMt_anULzGvWGNVy5wco8eN&amp;fref=mentions&amp;__xts__%5B0%5D=68.ARB1sO15keNPy0KYjgwc8lpBAKFEGY7HiyDoz5Iacy1vPP3_r4aONURDT9OsMg0ZCf2Nu0pzl-kNtoMMIWGlQsBwIhFnhhObmbCnJVJ_epkr7TLIuwULv-ypYwB_2PdxbNCs23CpfUW-6bl6Qk35SagmObo64A1FiGX7RRQfrGVcxehzkd8PTM-8ShNRAuIZvVCKXr7ldFi9ol7FdUyAGOArIJdCCboZYdg5I1fezAujQIUDosl-5dxn6MTIu52cSIWTFuXNT2HV9peMwDXY9fNOq9p0-gb1o9H-YbduTOOT1SZQ1OQ87bS0fCSvWSL7qavNZ1Bzwpox_pStQYSo5lAmnzRu\" data-hovercard=\"\/ajax\/hovercard\/user.php?id=1322852121&amp;extragetparams=%7B%22__tn__%22%3A%22%2CdK-R-R%22%2C%22eid%22%3A%22ARAU3Z1rGqia2cAcQKuXK9Z_K2D-dne6lEpoyDTdYrArqmvNWW6ax8ZjRSMt_anULzGvWGNVy5wco8eN%22%2C%22fref%22%3A%22mentions%22%7D\" data-hovercard-prefer-more-content-show=\"1\"><strong>Margalida Sans\u00f3 Jaume<\/strong><\/a> ha sido defensora de una de las v\u00edctimas del &#8220;tironero&#8221; de Manacor, que ayer se declar\u00f3 culpable de un homicidio imprudente y autor confeso de cinco robos con violencia en el lapso de cuatro d\u00edas en dicha localidad mallorquina hace dos a\u00f1os, noticia de la que se hizo eco el diario digital <a href=\"http:\/\/www.ultimahora.es\"><strong>\u00daltima Hora<\/strong><\/a><\/p>\n<p><a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/fmsb?source=feed_text&amp;epa=HASHTAG&amp;__xts__%5B0%5D=68.ARB1sO15keNPy0KYjgwc8lpBAKFEGY7HiyDoz5Iacy1vPP3_r4aONURDT9OsMg0ZCf2Nu0pzl-kNtoMMIWGlQsBwIhFnhhObmbCnJVJ_epkr7TLIuwULv-ypYwB_2PdxbNCs23CpfUW-6bl6Qk35SagmObo64A1FiGX7RRQfrGVcxehzkd8PTM-8ShNRAuIZvVCKXr7ldFi9ol7FdUyAGOArIJdCCboZYdg5I1fezAujQIUDosl-5dxn6MTIu52cSIWTFuXNT2HV9peMwDXY9fNOq9p0-gb1o9H-YbduTOOT1SZQ1OQ87bS0fCSvWSL7qavNZ1Bzwpox_pStQYSo5lAmnzRu&amp;__tn__=%2ANK-R\" data-ft=\"{&quot;type&quot;:104,&quot;tn&quot;:&quot;*N&quot;}\"><span class=\"_5afx\"><span class=\"_58cl _5afz\" aria-label=\"hashtag\">#<\/span><span class=\"_58cm\">fmsb<\/span><\/span><\/a> <a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/abogados?source=feed_text&amp;epa=HASHTAG&amp;__xts__%5B0%5D=68.ARB1sO15keNPy0KYjgwc8lpBAKFEGY7HiyDoz5Iacy1vPP3_r4aONURDT9OsMg0ZCf2Nu0pzl-kNtoMMIWGlQsBwIhFnhhObmbCnJVJ_epkr7TLIuwULv-ypYwB_2PdxbNCs23CpfUW-6bl6Qk35SagmObo64A1FiGX7RRQfrGVcxehzkd8PTM-8ShNRAuIZvVCKXr7ldFi9ol7FdUyAGOArIJdCCboZYdg5I1fezAujQIUDosl-5dxn6MTIu52cSIWTFuXNT2HV9peMwDXY9fNOq9p0-gb1o9H-YbduTOOT1SZQ1OQ87bS0fCSvWSL7qavNZ1Bzwpox_pStQYSo5lAmnzRu&amp;__tn__=%2ANK-R\" data-ft=\"{&quot;type&quot;:104,&quot;tn&quot;:&quot;*N&quot;}\"><span class=\"_5afx\"><span class=\"_58cl _5afz\" aria-label=\"hashtag\">#<\/span><span class=\"_58cm\">abogados<\/span><\/span><\/a> <a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/manacor?source=feed_text&amp;epa=HASHTAG&amp;__xts__%5B0%5D=68.ARB1sO15keNPy0KYjgwc8lpBAKFEGY7HiyDoz5Iacy1vPP3_r4aONURDT9OsMg0ZCf2Nu0pzl-kNtoMMIWGlQsBwIhFnhhObmbCnJVJ_epkr7TLIuwULv-ypYwB_2PdxbNCs23CpfUW-6bl6Qk35SagmObo64A1FiGX7RRQfrGVcxehzkd8PTM-8ShNRAuIZvVCKXr7ldFi9ol7FdUyAGOArIJdCCboZYdg5I1fezAujQIUDosl-5dxn6MTIu52cSIWTFuXNT2HV9peMwDXY9fNOq9p0-gb1o9H-YbduTOOT1SZQ1OQ87bS0fCSvWSL7qavNZ1Bzwpox_pStQYSo5lAmnzRu&amp;__tn__=%2ANK-R\" data-ft=\"{&quot;type&quot;:104,&quot;tn&quot;:&quot;*N&quot;}\"><span class=\"_5afx\"><span class=\"_58cl _5afz\" aria-label=\"hashtag\">#<\/span><span class=\"_58cm\">manacor<\/span><\/span><\/a><\/p>\n<h1><\/h1>\n<h1><strong>El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel<\/strong><\/h1>\n<p><a href=\"http:\/\/fmsb.disstintbeta.com\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-4780\" src=\"http:\/\/fmsb.disstintbeta.com\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg\" alt=\"\" width=\"800\" height=\"497\" srcset=\"https:\/\/font-mora-sainz-baranda.fra1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg 1181w, https:\/\/font-mora-sainz-baranda.fra1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1-300x186.jpg 300w, https:\/\/font-mora-sainz-baranda.fra1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1-1024x636.jpg 1024w, https:\/\/font-mora-sainz-baranda.fra1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1-768x477.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<div class=\"box valora clearfix\">\n<p class=\"autor autor_extras pull-left\"><a class=\"author\" href=\"https:\/\/www.ultimahora.es\/autor\/guillermo-esteban.html\" rel=\"author\">G.Esteban<\/a> | <a class=\"twitter\" href=\"https:\/\/twitter.com\/GuillEsteban\">@GuillEsteban<\/a> | Manacor | <time datetime=\"2020-07-24\">24\/07\/2020<\/time><\/p>\n<\/div>\n<div id=\"tabs-media\">\n<div class=\"lista_tab clearfix\">\n<div id=\"tabs-media-image\">\n<figure id=\"fotografia_wrapper\">\n<div class=\"big_img img_portada\"><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<aside class=\"box_social_print clearfix\">\n<div class=\"print_box clearfix pull-right\">El \u2018tironero\u2019 que <a href=\"https:\/\/www.ultimahora.es\/sucesos\/ultimas\/2018\/11\/05\/1036155\/detienen-autor-del-tiron-provoco-muerte-mujer-manacor.html\">provoc\u00f3 la muerte de una mujer en Manacor <\/a>en 2018 ha aceptado una<strong> condena de 12 a\u00f1os de c\u00e1rcel<\/strong>. Jamal Lamalmi, de origen marroqu\u00ed, se declar\u00f3 culpable ayer en el juicio de un delito de homicidio imprudente, cuatro robos con violencia y otro en casa habitada.<\/div>\n<\/aside>\n<div class=\"cuerpo\">\n<div class=\"letra3\">\n<p>El juez tuvo en cuenta las atenuantes de confesi\u00f3n, toxifrenia y reparaci\u00f3n del da\u00f1o, as\u00ed como las agravantes de reincidencia y de disfraz. El procesado ha consignado 1.000 euros para una de las perjudicadas, pero tendr\u00e1 que indemnizar al marido de la fallecida con m\u00e1s de <strong>113.000 por los da\u00f1os morales<\/strong> ocasionados. Mar\u00eda Ruiz ten\u00eda 61 a\u00f1os.<\/p>\n<p>La <a href=\"https:\/\/www.ultimahora.es\/sucesos\/ultimas\/2018\/11\/07\/1036561\/tironero-causo-muerte-mujer-manacor-confiesa-cuatro-robos.html\">oleada de robos empez\u00f3 el 31 de octubre<\/a>. El acusado se dirigi\u00f3 a un domicilio y<strong> rompi\u00f3 una de las ventanas<\/strong> para acceder al interior. Una vez dentro se apoder\u00f3 de dos televisores, una bicicleta de monta\u00f1a y cuatro relojes. La bici y los relojes fueron recuperados posteriormente por la Polic\u00eda Nacional y se los entregaron a sus propietarios.<\/p>\n<p>El 2 de noviembre por la ma\u00f1ana, el joven circulaba en bicicleta con la cabeza cubierta por una capucha cuando <strong>se acerc\u00f3 a una anciana de 81 a\u00f1os<\/strong> que caminaba por la plaza Santa Catalina. La abord\u00f3 por la espalda, le arranc\u00f3 el bolso de un tir\u00f3n y huy\u00f3. Ese mismo d\u00eda, sobre las 19.00 horas, asalt\u00f3 a Mar\u00eda Ruiz cuando caminaba por la calle Manuel Morales. Arranc\u00f3 su bolso de un tir\u00f3n y se dio a la fuga. <strong>La v\u00edctima cay\u00f3 y se golpe\u00f3 la cabeza contra el suelo<\/strong>. Sufri\u00f3 un traumatismo craneoencef\u00e1lico grave con afectaci\u00f3n a todas las estructuras del cr\u00e1neo. La mujer falleci\u00f3 dos d\u00edas despu\u00e9s en el hospital a consecuencia de las graves lesiones.<\/p>\n<p>Jamal Lamalmi volvi\u00f3 a actuar el 3 de noviembre. Se acerc\u00f3 a una mujer en la calle Econom Pere Bonnin y, tras forcejear, le quit\u00f3 el bolso y escap\u00f3 corriendo. La v\u00edctima sufri\u00f3 heridas. Media hora despu\u00e9s perpetr\u00f3 su \u00faltimo golpe en el Paseo del Ferrocarril. Iba a bordo de una bicicleta y arrebat\u00f3 el bolso a una mujer de 70 a\u00f1os por la espalda.<\/p>\n<p><strong>Un adicto a la coca\u00edna que perpetr\u00f3 cinco robos en cuatro d\u00edas en Manacor<\/strong><\/p>\n<p>Jamal Lamalmi confes\u00f3 los robos en el juzgado de Manacor tras ser detenido. El joven explic\u00f3 que sufr\u00eda adicci\u00f3n a la coca\u00edna y que perdi\u00f3 su trabajo como jardinero por su grave dependencia de la droga.<\/p>\n<p>El juez tuvo en cuenta la<strong> atenuante de toxifrenia<\/strong> este jueves en el juicio porque el acusado cometi\u00f3 los hechos por su adicci\u00f3n a las sustancias. La abogada de la defensa lleg\u00f3 a un acuerdo con la fiscal y con la letrada de una de las perjudicadas. La Fiscal\u00eda reclamaba al inicio del proceso una pena de 28 a\u00f1os de prisi\u00f3n.<\/p>\n<\/div>\n<p><strong>Fuente<\/strong>: diario digital <a href=\"http:\/\/www.ultimahora.es\"><strong>\u00daltima Hora<\/strong><\/a>.<\/p>\n<p><strong>Autor<\/strong>: <a href=\"https:\/\/www.ultimahora.es\/autor\/guillermo-esteban.html\"><strong>Guillermo Esteban<\/strong><\/a><\/p>\n<p>Enlace directo a la noticia, <a href=\"https:\/\/www.ultimahora.es\/sucesos\/ultimas\/2020\/07\/24\/1183293\/tironero-provoco-muerte-mujer-manacor-acepta-anos-carcel.html?utm_source=whatsapp&amp;utm_medium=web\">aqu\u00ed<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La abogada de Font Mora Sainz de Baranda Margalida Sans\u00f3 Jaume ha sido defensora de una de las v\u00edctimas del &#8220;tironero&#8221; de Manacor, que ayer se declar\u00f3 culpable de un homicidio imprudente y autor confeso de cinco robos con violencia en el lapso de cuatro d\u00edas en dicha localidad mallorquina hace dos a\u00f1os, noticia de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9342,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2149,2367,2152],"tags":[2156,2174,5616,2182,5617,2726,5618,5619],"class_list":["post-11634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en-2","category-derecho-penal-en","category-home-en-2","tag-abogados-en","tag-font-mora-sainz-de-baranda-en","tag-homicidio-en","tag-manacor-en","tag-marga-sanso-en","tag-margalida-sanso-en","tag-robo-con-violencia-en","tag-tironero-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel - FMSB Abogados y Economistas en Baleares<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel - FMSB Abogados y Economistas en Baleares\" \/>\n<meta property=\"og:description\" content=\"La abogada de Font Mora Sainz de Baranda Margalida Sans\u00f3 Jaume ha sido defensora de una de las v\u00edctimas del &#8220;tironero&#8221; de Manacor, que ayer se declar\u00f3 culpable de un homicidio imprudente y autor confeso de cinco robos con violencia en el lapso de cuatro d\u00edas en dicha localidad mallorquina hace dos a\u00f1os, noticia de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/\" \/>\n<meta property=\"og:site_name\" content=\"FMSB Abogados y Economistas en Baleares\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-28T07:49:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fmsb.eu\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"734\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fmsb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fmsb-disstint\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fmsb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/\"},\"author\":{\"name\":\"fmsb\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#\\\/schema\\\/person\\\/9fba7c70814b0cd34d35d655d36a4ca2\"},\"headline\":\"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel\",\"datePublished\":\"2020-07-28T07:49:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/\"},\"wordCount\":607,\"publisher\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmsb.eu\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg\",\"keywords\":[\"abogados\",\"font mora sainz de baranda\",\"homicidio\",\"Manacor\",\"marga sanso\",\"margalida sanso\",\"robo con violencia\",\"tironero\"],\"articleSection\":[\"blog\",\"Derecho Penal\",\"Home\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/\",\"url\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/\",\"name\":\"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel - FMSB Abogados y Economistas en Baleares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmsb.eu\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg\",\"datePublished\":\"2020-07-28T07:49:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fmsb.eu\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fmsb.eu\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg\",\"width\":1181,\"height\":734},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/2020\\\/07\\\/28\\\/marga-sanso-abogada-tironero-manacor-robo-violencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/\",\"name\":\"FMSB Abogados y Economistas en Baleares\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#organization\",\"name\":\"FMSB Abogados y Economistas en Baleares\",\"url\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fmsb.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/fmsb.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.svg\",\"width\":154,\"height\":52,\"caption\":\"FMSB Abogados y Economistas en Baleares\"},\"image\":{\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/#\\\/schema\\\/person\\\/9fba7c70814b0cd34d35d655d36a4ca2\",\"name\":\"fmsb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426f4d5b0ebcace85460caf87cdaaa193694b611e990615d87a13f322fb7ee7f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426f4d5b0ebcace85460caf87cdaaa193694b611e990615d87a13f322fb7ee7f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426f4d5b0ebcace85460caf87cdaaa193694b611e990615d87a13f322fb7ee7f?s=96&d=mm&r=g\",\"caption\":\"fmsb\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/fmsb-disstint\"],\"url\":\"https:\\\/\\\/fmsb.eu\\\/en\\\/author\\\/fmsb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel - FMSB Abogados y Economistas en Baleares","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/","og_locale":"en_US","og_type":"article","og_title":"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel - FMSB Abogados y Economistas en Baleares","og_description":"La abogada de Font Mora Sainz de Baranda Margalida Sans\u00f3 Jaume ha sido defensora de una de las v\u00edctimas del &#8220;tironero&#8221; de Manacor, que ayer se declar\u00f3 culpable de un homicidio imprudente y autor confeso de cinco robos con violencia en el lapso de cuatro d\u00edas en dicha localidad mallorquina hace dos a\u00f1os, noticia de [&hellip;]","og_url":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/","og_site_name":"FMSB Abogados y Economistas en Baleares","article_published_time":"2020-07-28T07:49:38+00:00","og_image":[{"width":1181,"height":734,"url":"https:\/\/fmsb.eu\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg","type":"image\/jpeg"}],"author":"fmsb","twitter_card":"summary_large_image","twitter_creator":"@fmsb-disstint","twitter_misc":{"Written by":"fmsb","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/#article","isPartOf":{"@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/"},"author":{"name":"fmsb","@id":"https:\/\/fmsb.eu\/en\/#\/schema\/person\/9fba7c70814b0cd34d35d655d36a4ca2"},"headline":"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel","datePublished":"2020-07-28T07:49:38+00:00","mainEntityOfPage":{"@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/"},"wordCount":607,"publisher":{"@id":"https:\/\/fmsb.eu\/en\/#organization"},"image":{"@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/#primaryimage"},"thumbnailUrl":"https:\/\/fmsb.eu\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg","keywords":["abogados","font mora sainz de baranda","homicidio","Manacor","marga sanso","margalida sanso","robo con violencia","tironero"],"articleSection":["blog","Derecho Penal","Home"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/","url":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/","name":"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel - FMSB Abogados y Economistas en Baleares","isPartOf":{"@id":"https:\/\/fmsb.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/#primaryimage"},"image":{"@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/#primaryimage"},"thumbnailUrl":"https:\/\/fmsb.eu\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg","datePublished":"2020-07-28T07:49:38+00:00","breadcrumb":{"@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/#primaryimage","url":"https:\/\/fmsb.eu\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg","contentUrl":"https:\/\/fmsb.eu\/wp-content\/uploads\/2020\/07\/FMSB-Abogados-Marga-Sanso-Tironero-1.jpg","width":1181,"height":734},{"@type":"BreadcrumbList","@id":"https:\/\/fmsb.eu\/en\/2020\/07\/28\/marga-sanso-abogada-tironero-manacor-robo-violencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fmsb.eu\/en\/"},{"@type":"ListItem","position":2,"name":"El \u2018tironero\u2019 que provoc\u00f3 la muerte de una mujer en Manacor acepta 12 a\u00f1os de c\u00e1rcel"}]},{"@type":"WebSite","@id":"https:\/\/fmsb.eu\/en\/#website","url":"https:\/\/fmsb.eu\/en\/","name":"FMSB Abogados y Economistas en Baleares","description":"","publisher":{"@id":"https:\/\/fmsb.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fmsb.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fmsb.eu\/en\/#organization","name":"FMSB Abogados y Economistas en Baleares","url":"https:\/\/fmsb.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fmsb.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fmsb.eu\/wp-content\/uploads\/2025\/02\/logo.svg","contentUrl":"https:\/\/fmsb.eu\/wp-content\/uploads\/2025\/02\/logo.svg","width":154,"height":52,"caption":"FMSB Abogados y Economistas en Baleares"},"image":{"@id":"https:\/\/fmsb.eu\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fmsb.eu\/en\/#\/schema\/person\/9fba7c70814b0cd34d35d655d36a4ca2","name":"fmsb","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/426f4d5b0ebcace85460caf87cdaaa193694b611e990615d87a13f322fb7ee7f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/426f4d5b0ebcace85460caf87cdaaa193694b611e990615d87a13f322fb7ee7f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/426f4d5b0ebcace85460caf87cdaaa193694b611e990615d87a13f322fb7ee7f?s=96&d=mm&r=g","caption":"fmsb"},"sameAs":["https:\/\/x.com\/fmsb-disstint"],"url":"https:\/\/fmsb.eu\/en\/author\/fmsb\/"}]}},"_links":{"self":[{"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/posts\/11634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/comments?post=11634"}],"version-history":[{"count":0,"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/posts\/11634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/media\/9342"}],"wp:attachment":[{"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/media?parent=11634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/categories?post=11634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmsb.eu\/en\/wp-json\/wp\/v2\/tags?post=11634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}